{"id":6789,"date":"2022-04-19T14:37:39","date_gmt":"2022-04-19T12:37:39","guid":{"rendered":"https:\/\/verdevillaggio.com\/contacts\/"},"modified":"2026-04-24T13:53:26","modified_gmt":"2026-04-24T11:53:26","slug":"contacts","status":"publish","type":"page","link":"https:\/\/verdevillaggio.com\/en\/contacts\/","title":{"rendered":"Contacts"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6789\" class=\"elementor elementor-6789 elementor-14\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d984598 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d984598\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b6d7337\" data-id=\"b6d7337\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fb8f9a elementor-widget elementor-widget-heading\" data-id=\"1fb8f9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">We are here for you!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5264125 elementor-widget elementor-widget-text-editor\" data-id=\"5264125\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contact us for further information or to book your stay at Al Verde Villaggio. We will be delighted to assist you and make your experience unforgettable.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c4178c elementor-widget elementor-widget-shortcode\" data-id=\"8c4178c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f7549-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"7549\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/6789#wpcf7-f7549-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"7549\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f7549-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<p><label> Name<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Email<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Phone<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Message<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea form-control\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn\" type=\"submit\" value=\"Submit\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"190\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2bf7fbe\" data-id=\"2bf7fbe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b50cfe elementor-widget elementor-widget-google_maps\" data-id=\"6b50cfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=De%20Le%2C%2011%2C%2011010%20Rumiod%20AO&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"De Le, 11, 11010 Rumiod AO\"\n\t\t\t\t\taria-label=\"De Le, 11, 11010 Rumiod AO\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94dd9a7 elementor-widget elementor-widget-eth_contact_info\" data-id=\"94dd9a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eth_contact_info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eth-contact-info\">\n\t\t\t<ul>\n\n\t\t\t<li>\n\n\t\t\t<a href=\"https:\/\/www.google.com\/maps\/@45.7208011,7.1996971,20z?entry=ttu\">\n\t\t\t\t<span class=\"icon\"><i aria-hidden=\"true\" class=\"fas fa-map-pin\"><\/i><\/span>\n\t\t\t\t<span class=\"title\">De Le, 24, 11010 Rumiod (AO)<\/span>\n\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t\t<li>\n\n\t\t\t<a href=\"mailto:info@verdevillaggio.com\">\n\t\t\t\t<span class=\"icon\"><i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i><\/span>\n\t\t\t\t<span class=\"title\">info@verdevillaggio.com<\/span>\n\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t\t<li>\n\n\t\t\t<a href=\"tel:+393497337877\">\n\t\t\t\t<span class=\"icon\"><i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i><\/span>\n\t\t\t\t<span class=\"title\">(+39) 349 733 7877<\/span>\n\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t\t<li>\n\n\t\t\t<a href=\"https:\/\/wa.me\/+393497337877\">\n\t\t\t\t<span class=\"icon\"><i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i><\/span>\n\t\t\t\t<span class=\"title\">Whatsapp<\/span>\n\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9795a1 elementor-widget elementor-widget-eth_social\" data-id=\"c9795a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eth_social.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t\t<div class=\"eth-social-media\">\r\n\t\r\n\t\t\t<a href=\"#\">\r\n\r\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t<a href=\"#\">\r\n\r\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t<a href=\"#\">\r\n\r\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t<a href=\"#\">\r\n\r\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-pinterest-p\"><\/i>\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t<a href=\"#\">\r\n\r\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-tripadvisor\"><\/i>\r\n\t\t\t<\/a>\r\n\r\n\t\t\t\t<\/div>\r\n\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>We are here for you! Contact us for further information or to book your stay at Al Verde Villaggio. We will be delighted to assist you and make your experience unforgettable. De Le, 24, 11010 Rumiod (AO) info@verdevillaggio.com (+39) 349 733 7877 Whatsapp<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6789","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contacts - Camere e appartamenti in Valle d&#039;Aosta - Al verde villaggio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/verdevillaggio.com\/en\/contacts\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contacts - Camere e appartamenti in Valle d&#039;Aosta - Al verde villaggio\" \/>\n<meta property=\"og:description\" content=\"We are here for you! Contact us for further information or to book your stay at Al Verde Villaggio. We will be delighted to assist you and make your experience unforgettable. De Le, 24, 11010 Rumiod (AO) info@verdevillaggio.com (+39) 349 733 7877 Whatsapp\" \/>\n<meta property=\"og:url\" content=\"https:\/\/verdevillaggio.com\/en\/contacts\/\" \/>\n<meta property=\"og:site_name\" content=\"Camere e appartamenti in Valle d&#039;Aosta - Al verde villaggio\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-24T11:53:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/verdevillaggio.com\\\/en\\\/contacts\\\/\",\"url\":\"https:\\\/\\\/verdevillaggio.com\\\/en\\\/contacts\\\/\",\"name\":\"Contacts - Camere e appartamenti in Valle d&#039;Aosta - Al verde villaggio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/verdevillaggio.com\\\/#website\"},\"datePublished\":\"2022-04-19T12:37:39+00:00\",\"dateModified\":\"2026-04-24T11:53:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/verdevillaggio.com\\\/en\\\/contacts\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/verdevillaggio.com\\\/en\\\/contacts\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/verdevillaggio.com\\\/en\\\/contacts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/verdevillaggio.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contacts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/verdevillaggio.com\\\/#website\",\"url\":\"https:\\\/\\\/verdevillaggio.com\\\/\",\"name\":\"Camere e appartamenti in Valle d'Aosta - Al verde villaggio\",\"description\":\"Camere e appartamenti in Valle d&#039;Aosta - Al verde villaggio\",\"publisher\":{\"@id\":\"https:\\\/\\\/verdevillaggio.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/verdevillaggio.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/verdevillaggio.com\\\/#organization\",\"name\":\"Camere e appartamenti in Valle d'Aosta - Al verde villaggio\",\"url\":\"https:\\\/\\\/verdevillaggio.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/verdevillaggio.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/verdevillaggio.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/appartamenti-valledaosta.png\",\"contentUrl\":\"https:\\\/\\\/verdevillaggio.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/appartamenti-valledaosta.png\",\"width\":700,\"height\":235,\"caption\":\"Camere e appartamenti in Valle d'Aosta - Al verde villaggio\"},\"image\":{\"@id\":\"https:\\\/\\\/verdevillaggio.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contacts - Camere e appartamenti in Valle d&#039;Aosta - Al verde villaggio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/verdevillaggio.com\/en\/contacts\/","og_locale":"en_US","og_type":"article","og_title":"Contacts - Camere e appartamenti in Valle d&#039;Aosta - Al verde villaggio","og_description":"We are here for you! Contact us for further information or to book your stay at Al Verde Villaggio. We will be delighted to assist you and make your experience unforgettable. De Le, 24, 11010 Rumiod (AO) info@verdevillaggio.com (+39) 349 733 7877 Whatsapp","og_url":"https:\/\/verdevillaggio.com\/en\/contacts\/","og_site_name":"Camere e appartamenti in Valle d&#039;Aosta - Al verde villaggio","article_modified_time":"2026-04-24T11:53:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/verdevillaggio.com\/en\/contacts\/","url":"https:\/\/verdevillaggio.com\/en\/contacts\/","name":"Contacts - Camere e appartamenti in Valle d&#039;Aosta - Al verde villaggio","isPartOf":{"@id":"https:\/\/verdevillaggio.com\/#website"},"datePublished":"2022-04-19T12:37:39+00:00","dateModified":"2026-04-24T11:53:26+00:00","breadcrumb":{"@id":"https:\/\/verdevillaggio.com\/en\/contacts\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/verdevillaggio.com\/en\/contacts\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/verdevillaggio.com\/en\/contacts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/verdevillaggio.com\/"},{"@type":"ListItem","position":2,"name":"Contacts"}]},{"@type":"WebSite","@id":"https:\/\/verdevillaggio.com\/#website","url":"https:\/\/verdevillaggio.com\/","name":"Camere e appartamenti in Valle d'Aosta - Al verde villaggio","description":"Camere e appartamenti in Valle d&#039;Aosta - Al verde villaggio","publisher":{"@id":"https:\/\/verdevillaggio.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/verdevillaggio.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/verdevillaggio.com\/#organization","name":"Camere e appartamenti in Valle d'Aosta - Al verde villaggio","url":"https:\/\/verdevillaggio.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/verdevillaggio.com\/#\/schema\/logo\/image\/","url":"https:\/\/verdevillaggio.com\/wp-content\/uploads\/2023\/05\/appartamenti-valledaosta.png","contentUrl":"https:\/\/verdevillaggio.com\/wp-content\/uploads\/2023\/05\/appartamenti-valledaosta.png","width":700,"height":235,"caption":"Camere e appartamenti in Valle d'Aosta - Al verde villaggio"},"image":{"@id":"https:\/\/verdevillaggio.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/verdevillaggio.com\/en\/wp-json\/wp\/v2\/pages\/6789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verdevillaggio.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/verdevillaggio.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/verdevillaggio.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/verdevillaggio.com\/en\/wp-json\/wp\/v2\/comments?post=6789"}],"version-history":[{"count":9,"href":"https:\/\/verdevillaggio.com\/en\/wp-json\/wp\/v2\/pages\/6789\/revisions"}],"predecessor-version":[{"id":7553,"href":"https:\/\/verdevillaggio.com\/en\/wp-json\/wp\/v2\/pages\/6789\/revisions\/7553"}],"wp:attachment":[{"href":"https:\/\/verdevillaggio.com\/en\/wp-json\/wp\/v2\/media?parent=6789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}